<br />
<b>Warning</b>:  Declaration of Jetpack_IXR_Client::query() should be compatible with IXR_Client::query(...$args) in <b>/home/www/wordpress/wp-content/plugins/jetpack/class.jetpack-ixr-client.php</b> on line <b>30</b><br />
{"id":2146,"date":"2023-04-27T09:54:51","date_gmt":"2023-04-27T07:54:51","guid":{"rendered":"http:\/\/utaellamarie-peter.de\/wordpress\/?p=2146"},"modified":"2023-04-27T09:56:55","modified_gmt":"2023-04-27T07:56:55","slug":"artbox-project-basel-2-0","status":"publish","type":"post","link":"https:\/\/utaellamarie-peter.de\/wordpress\/artbox-project-basel-2-0\/","title":{"rendered":"ArtBox Project Basel 2.0"},"content":{"rendered":"\n<p>Ich bin dabei <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"724\" src=\"http:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-1024x724.jpeg\" alt=\"\" class=\"wp-image-2148\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-1024x724.jpeg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-300x212.jpeg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-768x543.jpeg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-1536x1086.jpeg 1536w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-2048x1448.jpeg 2048w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Certificate_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-Kopie-1200x848.jpeg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"http:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-1024x1024.jpeg\" alt=\"\" class=\"wp-image-2149\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-1024x1024.jpeg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-300x300.jpeg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-150x150.jpeg 150w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-768x768.jpeg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-1536x1536.jpeg 1536w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-2048x2048.jpeg 2048w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/Social_Mackie-Messer_5x5BlSfdT4Ch27DvxLW5-1200x1200.jpeg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ich bin dabei<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/2146"}],"collection":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2146"}],"version-history":[{"count":3,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/2146\/revisions"}],"predecessor-version":[{"id":2152,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/2146\/revisions\/2152"}],"wp:attachment":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}