<br />
<b>Warning</b>:  Declaration of Jetpack_IXR_Client::query() should be compatible with IXR_Client::query(...$args) in <b>/home/www/wordpress/wp-content/plugins/jetpack/class.jetpack-ixr-client.php</b> on line <b>30</b><br />
{"id":3224,"date":"2025-10-01T06:33:49","date_gmt":"2025-10-01T04:33:49","guid":{"rendered":"https:\/\/utaellamarie-peter.de\/wordpress\/?p=3224"},"modified":"2025-10-31T07:17:00","modified_gmt":"2025-10-31T06:17:00","slug":"ausstellung-nacht-gedok-galerie","status":"publish","type":"post","link":"https:\/\/utaellamarie-peter.de\/wordpress\/ausstellung-nacht-gedok-galerie\/","title":{"rendered":"&#8218;Memories and future horizons&#8216;-NARTWORK a.p.s. Mailand"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"577\" src=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-1024x577.jpg\" alt=\"\" class=\"wp-image-3236\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-1024x577.jpg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-300x169.jpg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-768x433.jpg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-1536x865.jpg 1536w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-2048x1154.jpg 2048w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/cover-1200x676.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"720\" src=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork-1024x720.jpg\" alt=\"\" class=\"wp-image-3246\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork-1024x720.jpg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork-300x211.jpg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork-768x540.jpg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork-1200x844.jpg 1200w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/2025-10-22-Zertifikat-Nartwork.jpg 1338w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-1024x768.jpg\" alt=\"\" class=\"wp-image-3237\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-1024x768.jpg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-300x225.jpg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-768x576.jpg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-1536x1152.jpg 1536w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-2048x1536.jpg 2048w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA110729-1200x900.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-1024x768.jpg\" alt=\"\" class=\"wp-image-3238\" srcset=\"https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-1024x768.jpg 1024w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-300x225.jpg 300w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-768x576.jpg 768w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-1536x1152.jpg 1536w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-2048x1536.jpg 2048w, https:\/\/utaellamarie-peter.de\/wp-content\/uploads\/PA111034-1200x900.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/3224"}],"collection":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/comments?post=3224"}],"version-history":[{"count":3,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/3224\/revisions"}],"predecessor-version":[{"id":3247,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/posts\/3224\/revisions\/3247"}],"wp:attachment":[{"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/media?parent=3224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/categories?post=3224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utaellamarie-peter.de\/wordpress\/wp-json\/wp\/v2\/tags?post=3224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}